{"id":12613,"date":"2021-12-16T00:01:00","date_gmt":"2021-12-15T23:01:00","guid":{"rendered":"https:\/\/glm.ouryes.ch\/?p=12613"},"modified":"2023-04-15T10:42:58","modified_gmt":"2023-04-15T08:42:58","slug":"fue-impreciso-el-plan-de-dios","status":"publish","type":"post","link":"https:\/\/godloves.me\/es\/fue-impreciso-el-plan-de-dios\/","title":{"rendered":"\u00bfC\u00f3mo juzgamos el plan de Dios?"},"content":{"rendered":"\n<p>Uno puede acercarse a la Biblia desde distintas perspectivas. Intentamos entender toda la profundidad, la anchura, la altura y la longitud, todas las dimensiones de Dios (como dice la carta a los Efesios 3,18). En geometr\u00eda solo hay tres dimensiones. A nosotros nos falta la dimensi\u00f3n espiritual.<\/p>\n\n\n\n<p>Hay que subrayar que somos nosotros los que necesitamos aprender, y no Dios. Tenemos nuestras propias ideas y muchas veces forzamos a Dios para que encaje en ellas. Pero, lo siento, Dios no cambia su plan en funci\u00f3n de nuestros sue\u00f1os. Hoy, miles de a\u00f1os despu\u00e9s, con todos nuestros avances cient\u00edficos y tecnol\u00f3gicos, intentamos probar y explicar las cosas m\u00e1s relevantes que sucedieron entonces.<\/p>\n\n\n\n<p>Dejemos hablar al contexto de la Biblia. Una y otra vez, la historia ha demostrado que Dios puede escribir recto con renglones torcidos. \u00bfNo es emocionante que incluso Jes\u00fas (que es uno con Dios) no supiera la hora exacta de su segunda venida?<\/p>\n\n\n\n<p><strong>Conclusi\u00f3n:<\/strong> quien desconf\u00eda de la Biblia se pierde en su propio laberinto de pensamientos. Dios nunca pierde el control. \u00c9l es un padre justo y lleno de amor, con un coraz\u00f3n abierto para todos los que conf\u00edan en \u00e9l.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u2026 podr\u00e9is comprender con todos los creyentes cu\u00e1n ancho, largo, profundo y alto es el amor de Cristo. <\/p><p>Efesios 3,18<\/p><\/blockquote>\n\n\n\n<p><strong>Un consejo:<\/strong> \u00bfdejas que Dios intervenga en tus planes o intentas aferrarte a tus ideas y conceptos?<\/p>\n\n\n\n<p><a href=\"https:\/\/www.bibleserver.com\/NVI\/Romanos11%3A33-36\" target=\"_blank\" rel=\"noreferrer noopener\">Texto del d\u00eda: Romanos 11,33-36<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno puede acercarse a la Biblia desde distintas perspectivas. Intentamos entender toda la profundidad, la anchura, la altura y la longitud, todas las dimensiones de Dios (como dice la carta a los Efesios 3,18). En geometr\u00eda solo hay tres dimensiones. A nosotros nos falta la dimensi\u00f3n espiritual. Hay que subrayar que somos nosotros los que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[419,231],"tags":[],"class_list":["post-12613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es_blog","category-navidad"],"_links":{"self":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/comments?post=12613"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media\/21221"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media?parent=12613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/categories?post=12613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/tags?post=12613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}