{"id":12631,"date":"2021-12-22T00:01:00","date_gmt":"2021-12-21T23:01:00","guid":{"rendered":"https:\/\/glm.ouryes.ch\/?p=12631"},"modified":"2023-04-15T10:42:54","modified_gmt":"2023-04-15T08:42:54","slug":"tienen-algun-sentido-el-pesebre-la-cruz-y-la-corona","status":"publish","type":"post","link":"https:\/\/godloves.me\/es\/tienen-algun-sentido-el-pesebre-la-cruz-y-la-corona\/","title":{"rendered":"\u00bfQu\u00e9 sentido tienen el pesebre, la cruz y la corona?"},"content":{"rendered":"\n<p>Jes\u00fas ten\u00eda un prop\u00f3sito eterno que le fue dado antes de la creaci\u00f3n del mundo. Su Padre lo envi\u00f3 al mundo con el prop\u00f3sito de librarnos del pecado y de la culpa. Jes\u00fas declar\u00f3 varias veces que vino para cumplir la voluntad de su Padre (Juan 8,29).<\/p>\n\n\n\n<p>La Navidad es el humilde comienzo de la misi\u00f3n de Dios de rescatar a los seres humanos, y es una misi\u00f3n para todo el mundo. As\u00ed como el arco\u00edris es s\u00edmbolo de un pacto, as\u00ed tambi\u00e9n el pesebre, la cruz y la corona son s\u00edmbolos y pruebas de la gran fidelidad de Dios. Por medio de Jes\u00fas, Dios extiende su mano reconciliadora a todos. Ahora vivimos en la \u00e9poca de la gracia y la misericordia, en la que Dios ofrece perd\u00f3n, paz y una relaci\u00f3n profunda con \u00e9l. No dejemos pasar la oportunidad.<\/p>\n\n\n\n<p><strong>Conclusi\u00f3n:<\/strong> Jes\u00fas ha abierto la puerta al reino de los cielos por medio del pesebre (vida), la cruz (muerte) y la corona (resurrecci\u00f3n). \u00c9l es el Rey de los corazones y est\u00e1 esperando, no le dejemos fuera. Solo tenemos que pedirle que entre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A partir de entonces, Jes\u00fas comenz\u00f3 a explicar a sus disc\u00edpulos que tendr\u00eda que ir a Jerusal\u00e9n, y que los ancianos, los jefes de los sacerdotes y los maestros de la ley le har\u00edan sufrir mucho. Les dijo que lo iban a matar, pero que al tercer d\u00eda resucitar\u00eda. <\/p><p>Mateo 16,21<\/p><\/blockquote>\n\n\n\n<p><strong>Un consejo:<\/strong> hoy es tu d\u00eda de gracia. \u00bfAceptas su ofrecimiento y le abres la puerta?<\/p>\n\n\n\n<p>Texto del d\u00eda: <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bibleserver.com\/NVI\/Tito2%3A11-14\" target=\"_blank\">Tito 2,11-14 <\/a>y <a href=\"https:\/\/www.bibleserver.com\/NVI\/2%20Timoteo1%3A9-10\" target=\"_blank\" rel=\"noreferrer noopener\">2 Timoteo 1,9-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas ten\u00eda un prop\u00f3sito eterno que le fue dado antes de la creaci\u00f3n del mundo. Su Padre lo envi\u00f3 al mundo con el prop\u00f3sito de librarnos del pecado y de la culpa. Jes\u00fas declar\u00f3 varias veces que vino para cumplir la voluntad de su Padre (Juan 8,29). La Navidad es el humilde comienzo de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[419,231],"tags":[],"class_list":["post-12631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es_blog","category-navidad"],"_links":{"self":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/comments?post=12631"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media\/21280"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media?parent=12631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/categories?post=12631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/tags?post=12631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}