{"id":12634,"date":"2021-12-23T00:01:00","date_gmt":"2021-12-22T23:01:00","guid":{"rendered":"https:\/\/glm.ouryes.ch\/?p=12634"},"modified":"2023-04-15T10:42:54","modified_gmt":"2023-04-15T08:42:54","slug":"por-que-decimos-que-el-es-el-rey","status":"publish","type":"post","link":"https:\/\/godloves.me\/es\/por-que-decimos-que-el-es-el-rey\/","title":{"rendered":"\u00bfQui\u00e9n es tu Rey?"},"content":{"rendered":"\n<p>El profeta Zacar\u00edas habl\u00f3 del Rey de reyes quinientos a\u00f1os antes de la entrada de Jes\u00fas a la ciudad de Jerusal\u00e9n (Zacar\u00edas 9,9b). Era imposible no escuchar al pueblo d\u00e1ndole la bienvenida con ramas de palma y con gritos de \u201c\u00a1Hosana\u2026, bendito el que viene en el nombre del Se\u00f1or!\u201d. Esto enfureci\u00f3 a los l\u00edderes religiosos. Los celos les cegaron y no vieron el mensaje real del Mes\u00edas aut\u00e9ntico, al que de verdad deber\u00edan estar esperando.<\/p>\n\n\n\n<p>Se cumpli\u00f3 la profec\u00eda y los ciegos recibieron la vista de forma milagrosa, pero los que solo ten\u00edan una \u201cvista religiosa\u201d se volvieron ciegos al mensaje reconciliador de Dios. El odio los incit\u00f3 a perseguir a Jes\u00fas hasta llevarlo a la cruz.<\/p>\n\n\n\n<p><strong>Conclusi\u00f3n:<\/strong> la Navidad es la celebraci\u00f3n de cumplea\u00f1os del Rey de todos los reyes, a quien muchos rechazan incluso hoy. Tanto antes como ahora, hay muchas noticias falsas que intentan ocultar la verdad.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Tu rey viene a ti, justo y victorioso,<br>pero humilde, montado en un asno,<br>en un burrito, cr\u00eda de una asna.<\/p><p>Zacar\u00edas 9,9b<\/p><\/blockquote>\n\n\n\n<p><strong>Un consejo:<\/strong> anuncia las buenas noticias del Rey de reyes.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.bibleserver.com\/NVI\/Mateo21%3A1-11\" target=\"_blank\" rel=\"noreferrer noopener\">Texto del d\u00eda: Mateo 21,1-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El profeta Zacar\u00edas habl\u00f3 del Rey de reyes quinientos a\u00f1os antes de la entrada de Jes\u00fas a la ciudad de Jerusal\u00e9n (Zacar\u00edas 9,9b). Era imposible no escuchar al pueblo d\u00e1ndole la bienvenida con ramas de palma y con gritos de \u201c\u00a1Hosana\u2026, bendito el que viene en el nombre del Se\u00f1or!\u201d. Esto enfureci\u00f3 a los l\u00edderes [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[419,231],"tags":[],"class_list":["post-12634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es_blog","category-navidad"],"_links":{"self":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/comments?post=12634"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/12634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media\/21287"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media?parent=12634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/categories?post=12634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/tags?post=12634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}