{"id":16311,"date":"2023-04-10T00:24:00","date_gmt":"2023-04-09T22:24:00","guid":{"rendered":"https:\/\/glm.ouryes.ch\/?p=16311"},"modified":"2023-04-15T10:42:09","modified_gmt":"2023-04-15T08:42:09","slug":"hay-esperanza","status":"publish","type":"post","link":"https:\/\/godloves.me\/es\/hay-esperanza\/","title":{"rendered":"\u00bfHay esperanza?"},"content":{"rendered":"\n<p>Los romanos acabaron con la esperanza de la gente en aquel hombre de 33 a\u00f1os llamado Jes\u00fas que curaba a los enfermos. \u00bfPor qu\u00e9 le mataron sin raz\u00f3n ni escr\u00fapulo? Dos hombres de camino a Ema\u00fas discut\u00edan sobre ello. Se les uni\u00f3 un desconocido que no paraba de hacerles preguntas. Parec\u00eda no saber nada de los tr\u00e1gicos acontecimientos de los \u00faltimos d\u00edas. Aun as\u00ed, les explic\u00f3 que todo deb\u00eda ocurrir tal y como lo predijeron las Sagradas Escrituras. El debate fue tan intenso que invitaron al hombre a cenar. Cuando el \u201cdesconocido\u201d or\u00f3 dando gracias y parti\u00f3 el pan, reconocieron que era Jes\u00fas resucitado. \u00a1En ese mismo instante desapareci\u00f3! \u2013\u201c\u00bfNo es cierto que el coraz\u00f3n nos ard\u00eda en el pecho mientras nos ven\u00eda hablando por el camino y nos explicaba las Escrituras?\u201d, se dijeron el uno al otro.<\/p>\n\n\n\n<p>Poco despu\u00e9s, Jes\u00fas se reuni\u00f3 con los otros diez disc\u00edpulos que se hab\u00edan encerrado. \u2014\u201c\u00a1Que la paz sea con vosotros!\u201d. \u00a1Ense\u00f1\u00f3 sus manos y sus pies perforados por los clavos a los asustados hombres y comi\u00f3 con ellos! Con paciencia les explic\u00f3, a partir de la Palabra de Dios, que \u00e9l era el Salvador prometido. Jes\u00fas, la esperanza, era real, tangible, estaba justo en medio de ellos. \u00c9l est\u00e1 vivo, \u00e9l est\u00e1 ah\u00ed, puedes experimentarle, incluso hoy.<\/p>\n\n\n\n<p>Al igual que los disc\u00edpulos ten\u00edan todav\u00eda mucho que aprender, nosotros tambi\u00e9n. Podemos conocerle a trav\u00e9s de la Biblia y cuando creemos en \u00e9l podemos experimentarlo personalmente. Podemos hablar con \u00e9l y experimentar c\u00f3mo act\u00faa en nuestra vida. Jes\u00fas nos ofrece este camino de fe y confianza. A pesar de que en ese momento se le pod\u00eda ver f\u00edsicamente, muchos tampoco creyeron en \u00e9l. As\u00ed que no importa si le vemos o no. La fe significa esperar, sin ver todav\u00eda. Nosotros tenemos el privilegio de poder crecer en una verdadera y profunda relaci\u00f3n con \u00e9l.<\/p>\n\n\n\n<p>\u00bfQuieres una relaci\u00f3n personal y llena de esperanza con Jes\u00fas?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ved mis manos y mis pies: \u00a1soy yo mismo! Tocadme y mirad: un esp\u00edritu no tiene carne ni huesos como veis que yo tengo.<\/p><p>Al decirles esto, les mostr\u00f3 las manos y los pies.<\/p><p><em>Palabras de Jes\u00fas en Lucas 24:39-40<\/em><\/p><\/blockquote>\n\n\n\n<p><strong>Texto b\u00edblico para profundizar: <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bibleserver.com\/NVI\/Lucas24%3A13-49\" target=\"_blank\">Lucas 24:13-49<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hay esperanza? - ES\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/MnQBu1W5pzg?list=PLTYDhio7-SlxX6_M7i_y1I2EvqSuFz8bl\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los romanos acabaron con la esperanza de la gente en aquel hombre de 33 a\u00f1os llamado Jes\u00fas que curaba a los enfermos. \u00bfPor qu\u00e9 le mataron sin raz\u00f3n ni escr\u00fapulo? Dos hombres de camino a Ema\u00fas discut\u00edan sobre ello. Se les uni\u00f3 un desconocido que no paraba de hacerles preguntas. Parec\u00eda no saber nada de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[340,348,419],"tags":[],"class_list":["post-16311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-easter-es","category-easter_2022-es","category-es_blog"],"_links":{"self":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/16311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/comments?post=16311"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/posts\/16311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media\/22917"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/media?parent=16311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/categories?post=16311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/es\/wp-json\/wp\/v2\/tags?post=16311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}