{"id":4024,"date":"2020-11-22T00:03:00","date_gmt":"2020-11-22T00:03:00","guid":{"rendered":"https:\/\/glm.ouryes.ch\/?p=4024"},"modified":"2023-04-14T11:15:18","modified_gmt":"2023-04-14T09:15:18","slug":"tout-finit-dans-la-boite","status":"publish","type":"post","link":"https:\/\/godloves.me\/fr\/tout-finit-dans-la-boite\/","title":{"rendered":"Tout finit dans la bo\u00eete"},"content":{"rendered":"\n<p>Le Monopoly est l&rsquo;un de mes jeux pr\u00e9f\u00e9r\u00e9s. \u00c0 un moment donn\u00e9, j&rsquo;ai d\u00e9couvert comment gagner \u00e0 ce jeu : il faut tout acheter rapi- dement et avec avidit\u00e9. Quand je suis le roi du jeu et du c\u00f4t\u00e9 des vainqueurs, survient alors le pire moment : \u00e0 la fin, tout finit dans la bo\u00eete et le jeu est termin\u00e9.<\/p>\n\n\n\n<p>C&rsquo;est comme \u00e7a que \u00e7a fonctionne dans notre monde, dans nos vies. \u00c0 la fin, tout finit dans une bo\u00eete ou dans une urne. Et qu&rsquo;est-ce qui reste ? Dieu dit que seules les valeurs \u00e9ternelles demeurent : notre&nbsp;amour pour Dieu et les humains, son amour pour moi, car Dieu et&nbsp;les hommes sont des valeurs \u00e9ternelles. Tout le reste est passager.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Tu aimeras le Seigneur ton Dieu, de tout ton c\u0153ur, de toute ton \u00e2me, de toute ton \u00e9nergie et de toute ta pens\u00e9e, et ton prochain comme toi-m\u00eame.<\/p><cite>Luc 10,27<\/cite><\/blockquote>\n\n\n\n<p>Quelles sont vos priorit\u00e9s ? Les valeurs \u00e9ternelles ou passag\u00e8res ?&nbsp;<strong>Texte de la semaine :&nbsp;<\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.bibleserver.com\/BDS.S21\/Luc10%3A25-37\" target=\"_blank\">Luc 10,25\u201337<\/a><\/p>\n\n\n\n<p><strong>Quelles sont les vraies valeurs ?<\/strong><\/p>\n\n\n\n<p>Avez-vous des questions sur Dieu ou sur la Bible ?<br>Veuillez nous \u00e9crire sur \u202d+4177 533 61 78\u202d (SMS, WhatsApp)&nbsp;et nous vous r\u00e9pondrons avec plaisir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Monopoly est l&rsquo;un de mes jeux pr\u00e9f\u00e9r\u00e9s. \u00c0 un moment donn\u00e9, j&rsquo;ai d\u00e9couvert comment gagner \u00e0 ce jeu : il faut tout acheter rapi- dement et avec avidit\u00e9. Quand je suis le roi du jeu et du c\u00f4t\u00e9 des vainqueurs, survient alors le pire moment : \u00e0 la fin, tout finit dans la bo\u00eete [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[416,149],"tags":[],"class_list":["post-4024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fr_blog","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/posts\/4024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/comments?post=4024"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/posts\/4024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/media\/3467"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/media?parent=4024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/categories?post=4024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/fr\/wp-json\/wp\/v2\/tags?post=4024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}