{"id":32137,"date":"2023-08-20T00:37:00","date_gmt":"2023-08-19T22:37:00","guid":{"rendered":"https:\/\/godloves.me\/?p=32137"},"modified":"2023-07-08T12:47:32","modified_gmt":"2023-07-08T10:47:32","slug":"lohnt-sich-geduld","status":"publish","type":"post","link":"https:\/\/godloves.me\/pt-pt\/lohnt-sich-geduld\/","title":{"rendered":"Lohnt sich Geduld?"},"content":{"rendered":"\n<p>Mein Wecker schrillt unaufh\u00f6rlich. Halb tr\u00e4umend konfrontiert mich die kalte Realit\u00e4t! M\u00f6glichst schnell m\u00f6chte ich zur\u00fcck in die Welt der Tr\u00e4ume. Schlaftrunken, unmotiviert und mit winzig-kleinen Augen schleppe ich mich ins Bad. Sind dir solche Szenen auch bekannt?<\/p>\n\n\n\n<p>W\u00e4hrend \u00fcber zwei Jahren war das meine Morgenroutine. T\u00e4glich k\u00e4mpfte ich gegen die negativen Gedanken. Ich wollte sie besiegen.<\/p>\n\n\n\n<p>In jener Zeit f\u00fchlte ich mich v\u00f6llig fehl am Arbeitsplatz.&nbsp; Als ich jedoch mein Dilemma vor Gott ausbreitete, erfuhr ich seine Hilfe. Im Nachhinein kann ich seinen wunderbaren Plan darin erkennen.<\/p>\n\n\n\n<p>Lebst du aktuell in einer \u00e4hnlichen Situation? F\u00fchlst du dich am falschen Platz? Ist es vielleicht eine Zeit, in der du etwas Wichtiges lernen kannst? Vertrau deinem Sch\u00f6pfer. Er kennt dich genau.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Ihr werdet ihn immer besser kennen lernen und das ganze Ausmass seiner herrlichen Kraft und St\u00e4rke erfahren, damit ihr geduldig und ausdauernd euren Weg gehen k\u00f6nnt. <\/em><\/p>\n<cite><em>Kolosser 1,11<\/em><\/cite><\/blockquote>\n\n\n\n<p>Im richtigen Moment zeigt er dir den n\u00e4chsten Schritt. Bleib geduldig in seiner Gegenwart. Er wird dich daf\u00fcr t\u00e4glich mit neuer Kraft belohnen.<\/p>\n\n\n\n<p>Wie geht es dir mit der Geduld?<\/p>\n\n\n\n<p>Passender Bibeltext: <a href=\"https:\/\/www.bibleserver.com\/LUT\/Kolosser1%2C1-14\" target=\"_blank\" rel=\"noreferrer noopener\">Kolosser 1, 1-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Wecker schrillt unaufh\u00f6rlich. Halb tr\u00e4umend konfrontiert mich die kalte Realit\u00e4t! M\u00f6glichst schnell m\u00f6chte ich zur\u00fcck in die Welt der Tr\u00e4ume. Schlaftrunken, unmotiviert und mit winzig-kleinen Augen schleppe ich mich ins Bad. Sind dir solche Szenen auch bekannt? W\u00e4hrend \u00fcber zwei Jahren war das meine Morgenroutine. T\u00e4glich k\u00e4mpfte ich gegen die negativen Gedanken. Ich wollte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[420],"tags":[],"class_list":["post-32137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de_blog"],"_links":{"self":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts\/32137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/comments?post=32137"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts\/32137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/media\/30313"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/media?parent=32137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/categories?post=32137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/tags?post=32137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}