{"id":34958,"date":"2024-03-31T01:34:00","date_gmt":"2024-03-31T00:34:00","guid":{"rendered":"https:\/\/godloves.me\/?p=34958"},"modified":"2024-03-31T08:21:44","modified_gmt":"2024-03-31T06:21:44","slug":"christus-ist-auferstanden","status":"publish","type":"post","link":"https:\/\/godloves.me\/pt-pt\/christus-ist-auferstanden\/","title":{"rendered":"Christus ist auferstanden!"},"content":{"rendered":"\n<p>Jesus wird von einer Jungfrau geboren, vollbringt bemerkenswerte Wunder und gibt sogar sein Leben f\u00fcr uns Menschen hin. Aber ohne seine Auferstehung von den Toten ist diese Geschichte v\u00f6llig wertlos.<\/p>\n\n\n\n<p>Das Markusevangelium beschreibt, dass Frauen am Sonntagmorgen zu seinem Grab gehen und den Stein weggerollt sehen. Statt dass sie Jesus finden, sitzt dort ein Engel.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Er aber sprach zu ihnen: \u00abEntsetzt euch nicht! Ihr sucht Jesus von Nazareth, den Gekreuzigten. Er ist auferstanden, er ist nicht hier. Seht da die Stelle, wo sie ihn hingelegt haben!\u00bb<\/em><\/p>\n<cite><em><em><em><em>Markus 16,6<\/em><\/em><\/em><\/em><\/cite><\/blockquote>\n\n\n\n<p>Jesus wird am Karfreitag \u00f6ffentlich hingerichtet und nach seinem grausamen Tod in ein bewachtes und&nbsp; versiegeltes&nbsp; Grab gelegt. Und doch ist er drei Tage sp\u00e4ter wieder lebendig. Und zeigt sich im Laufe der n\u00e4chsten 40 Tage Maria Magdalena, drei anderen Frauen, seinen J\u00fcngern, seinem Halbbruder Jakobus und \u00fcber 500 weiteren Augenzeugen.<\/p>\n\n\n\n<p>All dies sollte uns ermutigen, sorgf\u00e4ltig zu pr\u00fcfen, was die historischen Berichte \u00fcber Jesus aussagen. Wir sollten \u00fcber die Tatsache nachdenken, dass Jesus der Erste war, der auferstanden ist, und dass er damit uns ewiges Leben schenken kann. Christus ist auferstanden!<\/p>\n\n\n\n<p>Was bedeutet es f\u00fcr dich, wenn Jesus tats\u00e4chlich auferstanden ist?<\/p>\n\n\n\n<p>Passender Bibeltext: <a href=\"https:\/\/www.bibleserver.com\/HFA\/Markus16%2C1-8\" target=\"_blank\" rel=\"noreferrer noopener\">Markus 16,1-8<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/godtime.online\/hoffnung-jesus-christus\/\" data-type=\"link\" data-id=\"https:\/\/godtime.online\/hoffnung-jesus-christus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hier<\/a> kannst du mehr \u00fcber die Hoffnung erfahren, was Jesus uns schenken kann.<\/p>\n\n\n\n<p>Hast du Fragen \u00fcber Gott oder die Bibel? Schreibe auf <a href=\"mailto:info@godloves.me\">input@godloves.me<\/a>&nbsp;oder WhatsApp +4177 533 61 78.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jesus wird von einer Jungfrau geboren, vollbringt bemerkenswerte Wunder und gibt sogar sein Leben f\u00fcr uns Menschen hin. Aber ohne seine Auferstehung von den Toten ist diese Geschichte v\u00f6llig wertlos. Das Markusevangelium beschreibt, dass Frauen am Sonntagmorgen zu seinem Grab gehen und den Stein weggerollt sehen. Statt dass sie Jesus finden, sitzt dort ein Engel. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[420],"tags":[],"class_list":["post-34958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de_blog"],"_links":{"self":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts\/34958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/comments?post=34958"}],"version-history":[{"count":0,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/posts\/34958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/media\/34934"}],"wp:attachment":[{"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/media?parent=34958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/categories?post=34958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/godloves.me\/pt-pt\/wp-json\/wp\/v2\/tags?post=34958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}